{"id":3289,"date":"2018-02-13T00:00:55","date_gmt":"2018-02-12T23:00:55","guid":{"rendered":"http:\/\/www.villapoggiosalvi.it\/wp2\/?p=3289"},"modified":"2018-02-21T17:31:26","modified_gmt":"2018-02-21T16:31:26","slug":"benvenuto-brunello-2018","status":"publish","type":"post","link":"https:\/\/www.villapoggiosalvi.it\/wp2\/2018\/02\/13\/benvenuto-brunello-2018\/","title":{"rendered":"BENVENUTO BRUNELLO 2018"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: center;\">Villa Poggio Salvi sar\u00e0 presente nei giorni <u><strong>18 e 19 febbraio<\/strong><\/u><strong>, <\/strong>dalle ore 10 alle 18, alla manifestazione<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 20px;\">Benvenuto Brunello 2018<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><img style=\"width: 460px; height: 295px; border-width: 1px; border-style: solid;\" src=\"http:\/\/www.villapoggiosalvi.it\/img\/bb2018.jpg\" alt=\"\" \/><\/p>\n<p style=\"text-align: center;\">Villa Poggio Salvi presenter\u00e0 in questa occasione i seguenti vini:<\/p>\n<p style=\"text-align: center;\"><strong>BRUNELLO di MONTALCINO DOCG 2013 CRU &#8211; POMONA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>BRUNELLO di MONTALCINO DOCG 2013 ANNATA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>BRUNELLO di MONTALCINO DOCG 2012 RISERVA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>ROSSO di MONTALCINO DOC 2016<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>***<\/strong><\/p>\n<p style=\"text-align: center;\">Per ulteriori informazioni:<br \/>\n<u><a href=\"http:\/\/www.consorziobrunellodimontalcino.it\" target=\"_blank\" rel=\"noopener\"><strong>www.consorziobrunellodimontalcino.it<\/strong><\/a><\/u><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Villa Poggio Salvi sar\u00e0 presente nei giorni 18 e 19 febbraio, dalle ore 10 alle 18, alla manifestazione Benvenuto Brunello 2018 Villa Poggio Salvi presenter\u00e0 in questa occasione i seguenti vini: BRUNELLO di MONTALCINO DOCG 2013 CRU &#8211; POMONA BRUNELLO di MONTALCINO DOCG 2013 ANNATA BRUNELLO di MONTALCINO DOCG 2012 RISERVA ROSSO di MONTALCINO DOC&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/www.villapoggiosalvi.it\/wp2\/2018\/02\/13\/benvenuto-brunello-2018\/\" class=\"gdlr-button with-border excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":3349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/posts\/3289"}],"collection":[{"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/comments?post=3289"}],"version-history":[{"count":3,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/posts\/3289\/revisions"}],"predecessor-version":[{"id":3344,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/posts\/3289\/revisions\/3344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/media\/3349"}],"wp:attachment":[{"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/media?parent=3289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/categories?post=3289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.villapoggiosalvi.it\/wp2\/wp-json\/wp\/v2\/tags?post=3289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}